{"id":4843,"date":"2023-03-12T08:33:26","date_gmt":"2023-03-12T07:33:26","guid":{"rendered":"https:\/\/xn--riveraindecarrire-6sb.be\/?page_id=4843"},"modified":"2023-08-12T08:57:43","modified_gmt":"2023-08-12T06:57:43","slug":"analyse-des-incidences-sur-lenvironnement-dun-permis-carrier","status":"publish","type":"page","link":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/analyse-juridique-dune-carriere\/elements-danalyse-dun-permis-carrier\/analyse-des-incidences-sur-lenvironnement-dun-permis-carrier\/","title":{"rendered":"Analyse des incidences sur l&rsquo;environnement d&rsquo;un permis carrier"},"content":{"rendered":"<p><strong><u>2\/ En ce qui concerne l&rsquo;\u00e9valuation des incidences du projet sur l\u2019environnement<\/u><\/strong><\/p>\n<p><u>2.1\/ Introduction \u00e0 la mati\u00e8re<\/u><\/p>\n<p><span style=\"text-decoration: underline;\">2.1.1\/ Base l\u00e9gale<\/span><\/p>\n<p>On rappellera que le si\u00e8ge de la mati\u00e8re est situ\u00e9 aux articles D.62 et svts du livre 1er du code de l\u2019environnement, qui indiquent:<\/p>\n<p><strong>D.62.<\/strong>\u00a0<strong>[<\/strong>\u00a7 1er. Toute demande de permis comporte soit une notice d\u2019\u00e9valuation des incidences sur l\u2019environnement, soit une \u00e9tude d\u2019incidences sur l\u2019environnement.<\/p>\n<ul>\n<li><strong> 2. Qu\u2019il s\u2019agisse de la notice d\u2019\u00e9valuation des incidences sur l\u2019environnement ou de l\u2019\u00e9tude d\u2019incidences sur l\u2019environnement, celle-ci identifie, d\u00e9crit et \u00e9value de mani\u00e8re appropri\u00e9e, en fonction de chaque cas particulier, les incidences directes et indirectes d\u2019un projet sur les facteurs suivants :<\/strong><\/li>\n<\/ul>\n<ol>\n<li><strong>a) la population et la sant\u00e9 humaine;<\/strong><\/li>\n<li><strong>b) la biodiversit\u00e9, en accordant une attention particuli\u00e8re aux esp\u00e8ces et aux habitats prot\u00e9g\u00e9s au titre de la directive 92\/43\/CEE et de la directive 2009\/147\/CE;<\/strong><\/li>\n<li><strong>c) les terres, le sol, le sous-sol, l\u2019eau, l\u2019air, le bruit, les vibrations, la mobilit\u00e9, l\u2019\u00e9nergie et le climat;<\/strong><\/li>\n<li><strong>d) les biens mat\u00e9riels, le patrimoine culturel et le paysage;<\/strong><\/li>\n<li><strong>e) l\u2019interaction entre les facteurs vis\u00e9s aux points a) \u00e0 d).<\/strong><\/li>\n<\/ol>\n<ul>\n<li>3 Les incidences, vis\u00e9es au paragraphe 2, sur les facteurs y \u00e9nonc\u00e9s englobent les incidences susceptibles de r\u00e9sulter de la vuln\u00e9rabilit\u00e9 du projet aux risques d\u2019accidents majeurs et\/ou de catastrophes pertinents pour le projet concern\u00e9.<strong>]<\/strong><br \/><strong>[D\u00e9cret 24.05.2018]<\/strong><\/li>\n<\/ul>\n<p><strong>Art. D.63. [<\/strong>La d\u00e9livrance de tout permis pour des projets susceptibles d\u2019avoir des incidences notables sur l\u2019environnement, notamment en raison de leur nature, de leurs dimensions ou de leur localisation est subordonn\u00e9e \u00e0 la mise en oeuvre d\u2019une \u00e9valuation de leurs incidences sur l\u2019environnement pr\u00e9vue par le pr\u00e9sent chapitre.<strong>]<\/strong><br \/>(1)\u00a0<strong>[D\u00e9cret 10.11.2006]\u00a0<\/strong>\u2013 (2)<strong>[D\u00e9cret 23.06.2016]\u00a0<\/strong>\u2013 (3)<strong>[D\u00e9cret 24.05.2018]<\/strong><\/p>\n<p><strong><em>Art. D.64.\u00a0<\/em><\/strong><em>\u00a7 1er. Les projets vis\u00e9s \u00e0 l\u2019annexe II sont soumis d\u2019office \u00e0 l\u2019\u00e9valuation des incidences sur l\u2019environnement.<\/em><\/p>\n<ul>\n<li><em> 2. Le Gouvernement arr\u00eate, la liste des projets qui, en raison de leur nature, de leurs dimensions ou de leur localisation, sont soumis \u00e0 l\u2019\u00e9valuation des incidences sur l\u2019environnement, compte tenu des crit\u00e8res de s\u00e9lection pertinents vis\u00e9s \u00e0 l\u2019annexe III.<\/em><\/li>\n<\/ul>\n<p>A cet \u00e9gard, les demandes de permis pour les projets sont soumis \u00e0 la r\u00e9daction d\u2019une notice d\u2019\u00e9valuation des incidences sur l\u2019environnement, \u00e0 moins que l\u2019ampleur du projet impose la r\u00e9alisation d\u2019une \u00e9tude d\u2019incidences sur l\u2019environnement.<\/p>\n<p>On rappelle que le contenu de l\u2019\u00e9valuation des incidences sur l\u2019environnement doit contenir en application de l\u2019article D.62du livre 1er du code de l\u2019environnement:<\/p>\n<p><span style=\"text-decoration: underline;\">2.1.2\/ Objectifs de\u00a0 l&rsquo;\u00e9valuation des incidences sur l&rsquo;environnement<\/span><\/p>\n<p>Le conseil d\u2019Etat enseigne de mani\u00e8re constante que l\u2019\u00e9valuation des incidences sur l\u2019environnement du projet doit permettre:<\/p>\n<ul>\n<li>\u00c0 l\u2019autorit\u00e9 de statuer en connaissance de cause<\/li>\n<\/ul>\n<p><em>\u00ab\u00a0De ce qui pr\u00e9c\u00e8de, il semble que la connaissance du gisement ne soit pas<\/em><br \/><em>sp\u00e9cialement pr\u00e9cise et que, d\u00e8s lors, le seul plan d&rsquo;exploitation bas\u00e9 sur une<\/em><br \/><em>activit\u00e9 d&rsquo;extraction de 30 ans, tant au niveau du phasage de l&rsquo;extraction qu&rsquo;en<\/em><br \/><em>mati\u00e8re de quantit\u00e9 de st\u00e9riles qui pourraient se pr\u00e9senter au cours de<\/em><br \/><em>l&rsquo;exploitation,<strong> ne permet pas \u00e0 l&rsquo;autorit\u00e9 comp\u00e9tente de prendre une d\u00e9cision en<\/strong><\/em><br \/><em><strong>toute connaissance de cause<\/strong>\u00a0\u00bb\u00a0(CE,\u00a0 247.547, 14 mai 2020, Cimenteries\u00a0 CBR, p. 34)<\/em><\/p>\n<ul>\n<li>Au public de faire valoir ses observations en connaissance de cause<\/li>\n<\/ul>\n<p><em>\u00ab\u00a0En consid\u00e9rant que l&rsquo;\u00e9tude d&rsquo;incidences n&rsquo;a pas rencontr\u00e9 cet objectif, le fonctionnaire technique et l&rsquo;auteur de l&rsquo;acte attaqu\u00e9 ne commettent pas d&rsquo;erreur puisque l&rsquo;AWAC rel\u00e8ve elle-m\u00eame dans son avis que ni l&rsquo;\u00e9valuation de la situation initiale, ni l&rsquo;\u00e9valuation de la situation projet\u00e9e ne contiennent la moindre quantification des \u00e9missions de poussi\u00e8res et de particules fines, ni d&rsquo;estimation de l&rsquo;impact du projet sur le voisinage. <strong>Partant, le public n&rsquo;a pas \u00e9t\u00e9 en mesure de formuler en toute connaissance de cause des observations \u00e0 cet \u00e9gard,<\/strong> et notamment au \u00a0sujet \u00a0de \u00a0l&rsquo;ad\u00e9quation \u00a0des \u00a0mesures \u00a0et\u00a0 recommandations\u00a0 sugg\u00e9r\u00e9es \u00a0dans \u00a0la demande, dans l&rsquo;\u00e9tude d&rsquo;incidences et dans les avis de l&rsquo;AWAC pour limiter ces nuisances.\u00a0\u00bb<\/em> (<em>CE,\u00a0 247.547, 14 mai 2020, Cimenteries\u00a0 CBR, p. 26)<\/em><\/p>\n<p><span style=\"text-decoration: underline;\">2.1.3\/ En ce qui concerne les conditions g\u00e9n\u00e9rales, sectorielles, int\u00e9grales et particuli\u00e8res<\/span><\/p>\n<p>Le conseil d&rsquo;\u00e9tat en enseigne:<\/p>\n<p><em>\u00ab\u00a0En vertu du d\u00e9cret du 11 mars 1999 relatif au permis d\u2019environnement, les conditions d\u2019exploitation des \u00e9tablissements class\u00e9s sont fix\u00e9es par des conditions g\u00e9n\u00e9rales, sectorielles ou int\u00e9grales, qui ont valeur r\u00e9glementaire, ou par des conditions particuli\u00e8res compl\u00e9mentaires. Les conditions g\u00e9n\u00e9rales s\u2019appliquent \u00e0 l\u2019ensemble des installations et activit\u00e9s. Les conditions sectorielles s\u2019appliquent aux installations et activit\u00e9s d\u2019un secteur \u00e9conomique, territorial ou dans lequel un risque particulier appara\u00eet ou peut appara\u00eetre. <strong>Les conditions particuli\u00e8res compl\u00e9mentaires ne peuvent \u00eatre moins s\u00e9v\u00e8res que les conditions g\u00e9n\u00e9rales et sectorielles, sauf dans les cas et limites arr\u00eat\u00e9s par lesdites conditions g\u00e9n\u00e9rales<\/strong>.\u00a0\u00bb\u00a0<\/em>(CE, 253.617, Couplet, 2 mai 2002, p. 52)<\/p>\n<p>Le conseil d&rsquo;Etat a pu r\u00e9cemment indiqu\u00e9 que des conditions particuli\u00e8res moins s\u00e9v\u00e8res que les conditions g\u00e9n\u00e9rales et sectorielles, ne pouvaient \u00eatre ind\u00e9finies, sous peine d&rsquo;\u00eatre consid\u00e9r\u00e9es comme des exon\u00e9rations (CE, 252.998\/9, Les versants de la Dyle, 16 f\u00e9vrier 2022).<\/p>\n<p><span style=\"text-decoration: underline;\">2.1.4\/ En ce qui concerne\u00a0 les contraintes quant au r\u00e9sultat \u00e0 atteindre<\/span><\/p>\n<p>Le conseil d&rsquo;Etat enseigne:<\/p>\n<p><em>\u00ab\u00a0Consid\u00e9rant que les<strong> normes d&rsquo;immission pr\u00e9cit\u00e9es s&rsquo;imposent \u00e0 l&rsquo;exploitant pour qui elles sont une obligation de r\u00e9sultat<\/strong>; que la requ\u00e9rante se borne \u00e0 affirmer que les \u00e9l\u00e9ments du projet ainsi d\u00e9crits ne permettent pas le respect de ces normes; qu&rsquo;elle ne produit toutefois aucune analyse technique de nature \u00e0 remettre en cause l&rsquo;avis du service sp\u00e9cialis\u00e9 qui n&rsquo;a pas sugg\u00e9r\u00e9 de mesures particuli\u00e8res;\u00a0\u00bb\u00a0<\/em>(CE, 236.447, Ville de Li\u00e8ge, 17 novembre 2016, p. 18)<\/p>\n<p><span style=\"text-decoration: underline;\">2.1.5\/ En ce qui concerne la capacit\u00e9 de l&rsquo;auteur de projet de faire face aux obligations impos\u00e9es par le permis<\/span><\/p>\n<p>Le conseil d\u2019\u00e9tat enseigne :<\/p>\n<p><em>\u00ab A l\u2019occasion de la d\u00e9livrance du permis, <strong>l\u2019autorit\u00e9 doit s\u2019assurer que l\u2019obligation ainsi faite \u00e0 l\u2019exploitant est possible<\/strong>, cad que l\u2019installation est capable d\u2019atteindre ledit r\u00e9sultat \u00bb (<\/em>CE, 232.220, Commune\u00a0de Momignies, 16 septembre 2016, p. 18)<\/p>\n<p><u>2.2\/ En ce qui concerne la motivation du permis en mati\u00e8re d\u2019incidences sur l\u2019environnement<\/u><\/p>\n<p>L\u2019article D.75 du livre 1er du code de l\u2019environnement pr\u00e9cise sp\u00e9cifiquement en cette mati\u00e8re:<\/p>\n<p><strong>Art. D.75.<\/strong>\u00a0<strong>[<\/strong>\u00a7 1er. Le permis et le refus de permis sont motiv\u00e9s en regard notamment des incidences sur l\u2019environnement et des objectifs de l\u2019article D.50.<\/p>\n<p>Ils contiennent \u00e9galement les motivations relatives \u00e0 la d\u00e9cision d\u2019imposer ou non une \u00e9tude d\u2019incidences vis\u00e9e \u00e0 l\u2019article D65.<\/p>\n<p>(\u2026)<\/p>\n<p>On trouvera ci-apr\u00e8s l\u2019article D.50 du livre 1er code de l\u2019environnement:<\/p>\n<p><strong><em>Art. D.50.\u00a0<\/em><\/strong><em>La mise en \u0153uvre\u00a0des proc\u00e9dures pr\u00e9vues par la pr\u00e9sente partie doit avoir principalement pour but<\/em>\u00a0:<\/p>\n<p>\u2013\u00a0<em>de prot\u00e9ger et d\u2019am\u00e9liorer la qualit\u00e9 du cadre de vie et des conditions de vie de la population, pour lui assurer un environnement sain, s\u00fbr et agr\u00e9able;<\/em><\/p>\n<p>\u2013<em>\u00a0de g\u00e9rer le milieu de vie et les ressources naturelles, de fa\u00e7on \u00e0 pr\u00e9server leurs qualit\u00e9s et \u00e0 utiliser rationnellement et judicieusement leurs potentialit\u00e9s<\/em>;<\/p>\n<p>\u2013\u00a0<em>d\u2019instaurer entre les besoins humains et le milieu de vie un \u00e9quilibre qui permette \u00e0 l\u2019ensemble de la population de jouir durablement d\u2019un cadre et de conditions de vie convenables;<\/em><\/p>\n<p>\u2013\u00a0<em>d\u2019assurer un niveau \u00e9lev\u00e9 de protection de l\u2019environnement et de contribuer \u00e0 l\u2019int\u00e9gration de consid\u00e9rations environnementales dans l\u2019\u00e9laboration et l\u2019adoption des plans et des<\/em>\u00a0<em>programmes susceptibles d\u2019avoir des incidences non n\u00e9gligeables sur l\u2019environnement en vue de promouvoir un d\u00e9veloppement durable.<\/em><\/p>\n<p>Le conseil d\u2019\u00e9tat enseigne \u00e0 ce niveau:<\/p>\n<p><strong>\u00ab\u00a0<em>La motivation impos\u00e9e par l\u2019article D.64\u00a0<\/em><\/strong>(actuellement le D.75)<em>\u00a0pr\u00e9cit\u00e9, du Livre Ier du Code de l\u2019environnement\u00a0<strong>relativement \u00e0 toutes les incidences d\u2019un projet, notables ou non,\u00a0<\/strong>et aux objectifs pr\u00e9cis\u00e9s \u00e0 l\u2019article D.50 du m\u00eame Code, doit \u00eatre proportionn\u00e9e \u00e0 la<\/em><br \/><em>nature du projet en question. Il faut notamment que la motivation de l\u2019acte et les<\/em><br \/><em>conditions qui l\u2019assortissent permettent de s\u2019assurer que l\u2019autorit\u00e9 comp\u00e9tente a<\/em><br \/><em>r\u00e9guli\u00e8rement v\u00e9rifi\u00e9 que, compte tenu des am\u00e9nagements pr\u00e9vus, les nuisances<\/em><br \/><em>resteraient dans des limites acceptables pour le voisinage. En revanche, les articles<\/em><br \/><em>D.50 et D.64 de ce Code n\u2019imposent pas que la d\u00e9livrance d\u2019un permis d\u2019urbanisme<\/em><br \/>ait pour effet d\u2019apporter une am\u00e9lioration au cadre de vie des riverains.\u00a0\u00bb (CE, Commune de Court-Saint-Etienne, 249.340 du 28 d\u00e9cembre 2020, p. 43).<\/p>\n<p><u>2.3\/ En ce qui concerne la notice d\u2019\u00e9valuation des incidences sur l\u2019environnement,<\/u><\/p>\n<p><span style=\"text-decoration: underline;\">L\u2019article D.66 du livre 1er du code de l\u2019environnement<\/span> pr\u00e9cise:<\/p>\n<p><em>\u00ab\u00a0Art. D.66. [\u00a7 1er. La notice d\u2019\u00e9valuation des incidences comporte au minimum les informations suivantes :<\/em><\/p>\n<p><em>1\u00b0 une description du projet, y<\/em>\u00a0compris<em>\u00a0en particulier :<\/em><\/p>\n<ol>\n<li><em>a) une description des caract\u00e9ristiques physiques de l\u2019ensemble du projet et, le cas \u00e9ch\u00e9ant, des travaux de d\u00e9molition;<\/em><\/li>\n<li><em>b) une description de la localisation du projet, en accordant une attention particuli\u00e8re \u00e0 la sensibilit\u00e9 environnementale des zones g\u00e9ographiques susceptibles d\u2019\u00eatre affect\u00e9es;<\/em><\/li>\n<\/ol>\n<p><em>2\u00b0 une description des \u00e9l\u00e9ments de l\u2019environnement susceptibles d\u2019\u00eatre affect\u00e9s de mani\u00e8re notable par le projet;<\/em><\/p>\n<p><em>3\u00b0 une description de tous les effets notables, dans la mesure des informations disponibles sur ces effets, que le projet est susceptible d\u2019avoir sur l\u2019environnement r\u00e9sultant :<\/em><\/p>\n<ol>\n<li><em>a) des r\u00e9sidus et des \u00e9missions attendus ainsi que de la production de d\u00e9chets, le cas \u00e9ch\u00e9ant;<\/em><\/li>\n<li><em>b) de l\u2019utilisation des ressources naturelles, en particulier le sol, les terres, l\u2019eau et la biodiversit\u00e9;<\/em><\/li>\n<\/ol>\n<p><em>4\u00b0 il est tenu compte des crit\u00e8res de l\u2019annexe III, le cas \u00e9ch\u00e9ant, lors de la compilation des informations conform\u00e9ment aux points 1\u00b0 \u00e0 3\u00b0.<\/em><\/p>\n<ul>\n<li><em> 2. Le Gouvernement peut arr\u00eater les formes et compl\u00e9ter le contenu minimal de la notice d\u2019\u00e9valuation des incidences sur l\u2019environnement. Il peut pr\u00e9voir que le dossier de demande de permis constitue la notice d\u2019\u00e9valuation des incidences sur l\u2019environnement.<\/em><\/li>\n<\/ul>\n<p><em>(\u2026)<\/em>\u00ab<\/p>\n<p>Le conseil d\u2019\u00e9tat \u00e0 r\u00e9cemment rappel\u00e9 sa jurisprudence dans l\u2019arr\u00eat\u00a0 n\u00b0249.340 en cause Commune de Court-Saint-Etienne (p. 33):<\/p>\n<p><em>\u00ab\u00a0La notice d\u2019\u00e9valuation des incidences sur l\u2019environnement est un<\/em><br \/><em>document qui doit permettre \u00e0 l\u2019autorit\u00e9 de refuser ou d\u00e9livrer un permis en toute<\/em><br \/><em>connaissance de cause quant aux incidences sur l\u2019environnement du projet soumis \u00e0<\/em><br \/><em>autorisation. D\u00e8s lors, la notice doit contenir des renseignements complets, pr\u00e9cis et<\/em><br \/><em>exacts. Les d\u00e9fauts dont elle serait affect\u00e9e ne peuvent toutefois entra\u00eener<\/em><br \/><em>l\u2019annulation de l\u2019autorisation que si cette derni\u00e8re a \u00e9t\u00e9 accord\u00e9e en m\u00e9connaissance<\/em><br \/><em>de cause par l\u2019autorit\u00e9, celle-ci n\u2019ayant \u00e9t\u00e9 compl\u00e8tement et exactement inform\u00e9e ni<\/em><br \/><em>par la notice d\u2019\u00e9valuation des incidences ni d\u2019une autre mani\u00e8re.\u00a0\u00bb<\/em><\/p>\n<p>Face \u00e0 des \u00e9l\u00e9ments lacunaires dans une notice d\u2019\u00e9valuation des incidences sur l\u2019environnement, le conseil d\u2019\u00e9tat pr\u00e9cise quant \u00e0 l\u2019autorit\u00e9:<\/p>\n<p><em>\u00ab\u00a0Il r\u00e9sulte de ce qui pr\u00e9c\u00e8de que l\u2019autorit\u00e9 ne disposait pas de\u00a0renseignements complets, pr\u00e9cis et exacts concernant le bassin d\u2019orage et qu\u2019elle\u00a0n\u2019\u00e9tait par cons\u00e9quent pas en mesure de statuer en toute connaissance de cause sur la\u00a0probl\u00e9matique du ruissellement des eaux.\u00a0\u00bb (CE, Commune de Court-Saint-Etienne, 249.340 du 28 d\u00e9cembre 2020, p. 43).<\/em><\/p>\n<p><span style=\"text-decoration: underline;\">L\u00a0\u00bbancien article D67 du livre Ier du code de l&rsquo;environnement<\/span> ajoutait encore::<\/p>\n<p class=\"justifie\"><em><strong>\u00ab\u00a0Art. 67. <\/strong>\u00a7 1<sup>er<\/sup>. Le Gouvernement arr\u00eate les formes et le contenu minimal de la notice d&rsquo;\u00e9valuation des incidences sur l&rsquo;environnement. Il peut pr\u00e9voir que le dossier de demande de permis constitue la notice d&rsquo;\u00e9valuation des incidences sur l&rsquo;environnement.<\/em><\/p>\n<p class=\"justifie\"><em>\u00a7 2. Le Gouvernement peut arr\u00eater les formes et le contenu minimal de l&rsquo;\u00e9tude d&rsquo;incidences sur l&rsquo;environnement.<\/em><\/p>\n<p class=\"justifie\"><em>\u00a7 3. La notice d&rsquo;\u00e9valuation des incidences ou l&rsquo;\u00e9tude d&rsquo;incidences comportent au minimum les informations suivantes :<\/em><\/p>\n<p class=\"justifie\"><em>1\u00b0 une description du projet comportant des informations relatives \u00e0 son site, \u00e0 sa conception et \u00e0 ses dimensions;<\/em><\/p>\n<p class=\"justifie\"><em>2\u00b0 les donn\u00e9es n\u00e9cessaires pour identifier et \u00e9valuer les effets principaux que le projet est susceptible d&rsquo;avoir sur l&rsquo;environnement;<\/em><\/p>\n<p class=\"justifie\"><em>3\u00b0 une description des mesures envisag\u00e9es pour \u00e9viter et r\u00e9duire les effets n\u00e9gatifs importants et, si possible, pour y rem\u00e9dier;<\/em><\/p>\n<p class=\"justifie\"><em>4\u00b0 une esquisse des principales solutions de substitution qui ont \u00e9t\u00e9 examin\u00e9es\u00a0<b>[<\/b>par l&rsquo;auteur d&rsquo;\u00e9tudes d&rsquo;incidences ou<b>]<\/b>\u00a0par le demandeur et une indication des principales raisons\u00a0<b>[<\/b>du choix de ce dernier<b>]<\/b>, eu \u00e9gard aux effets sur l&rsquo;environnement;<\/em><\/p>\n<p class=\"justifie\">5\u00b0 un r\u00e9sum\u00e9 non technique des points mentionn\u00e9s ci-dessus.<\/p>\n<p class=\"justifie\">Le Gouvernement d\u00e9termine les modalit\u00e9s suivant lesquelles, lorsqu&rsquo;elle est sollicit\u00e9e par le demandeur, l&rsquo;autorit\u00e9 comp\u00e9tente rend un avis sur les informations \u00e0 fournir dans la notice d&rsquo;\u00e9valuation ou dans l&rsquo;\u00e9tude d&rsquo;incidences.<br \/><b>[D\u00e9cret 10.11.2006]\u00a0\u00bb<\/b><\/p>\n<p>Le conseil d&rsquo;\u00e9tat a r\u00e9cemment jug\u00e9:<\/p>\n<p>&#8211; arr\u00eat 252.449, 16 d\u00e9cembre 2021, Stas de Richelle: pr\u00e9cision du conseil d&rsquo;Etat dans les termes suivants:<\/p>\n<p><em>\u00ab\u00a0si l&rsquo;auteur de la notice n&rsquo;est pas tenu d&rsquo;exposer toutes les alternatives possibles, il se doit, en revanche, d&rsquo;esquisser les principales solutions de substitution\u00a0 et d&rsquo;indiquer les principales raisons de son choix eu \u00e9gard aux effets sur l&rsquo;environnement\u00a0<\/em><\/p>\n<p><em>(&#8230;)<\/em><\/p>\n<p><em>L\u2019examen des alternatives concerne l\u2019impact paysager, sp\u00e9cialement lorsque, comme en l\u2019esp\u00e8ce, le projet se trouve dans un p\u00e9rim\u00e8tre d\u2019int\u00e9r\u00eat paysager, mais \u00e9galement les autres \u00e9l\u00e9ments de l\u2019environnement. Ainsi, le demandeur de permis dans une zone agricole d\u2019int\u00e9r\u00eat paysager doit au pr\u00e9alable chercher la localisation la moins pr\u00e9judiciable \u00e0 l\u2019environnement, dans toutes ses dimensions, et rendre compte de l\u2019examen des principales solutions de substitution au projet qu\u2019il a envisag\u00e9es, en tout cas sur les biens dont il a une ma\u00eetrise suffisante.\u00a0\u00bb<\/em><\/p>\n<p>&#8211; arr\u00eat 252.523, 22 d\u00e9cembre 2021, Bauvir: pr\u00e9cision quant\u00a0 la notion d&rsquo;esquisse et pr\u00e9cision quant \u00e0 une parcelle d\u00e9j\u00e0 construite<\/p>\n<p>&#8211; arr\u00eat 252.826, 28 janvier 2022, Dirvry: pr\u00e9cision quant \u00e0 la motivation du permis quant aux observations \u00e9mises lors de l&rsquo;enqu\u00eate publique quant aux solutions de substitution<\/p>\n<p><span style=\"text-decoration: underline;\">2.4\/ En ce qui concerne l\u2019\u00e9tude d\u2019incidences sur\u00a0 l\u2019environnement<\/span><\/p>\n<p><span style=\"text-decoration: underline;\">2.4.1\/ Base l\u00e9gale<\/span><\/p>\n<p>\u2019article D.67 du livre 1er du code de l\u2019environnement pr\u00e9cise:<\/p>\n<p><strong><em>\u00ab\u00a0<\/em><\/strong><em>Art. D.67<strong>. [<\/strong>\u00a7 1er. Le demandeur pr\u00e9pare et pr\u00e9sente une \u00e9tude d\u2019incidences qui comporte au minimum les informations suivantes :<\/em><\/p>\n<p><em>1\u00b0 une description du projet, et, le cas \u00e9ch\u00e9ant, des travaux de d\u00e9molition comportant des informations relatives \u00e0 son site d\u2019implantation, \u00e0 sa conception, \u00e0 ses dimensions et \u00e0 ses caract\u00e9ristiques pertinentes;<\/em><\/p>\n<p><em>2\u00b0 une description des incidences notables probables du projet sur l\u2019environnement;<\/em><\/p>\n<p><em>3\u00b0 une description des caract\u00e9ristiques du projet et\/ou des mesures envisag\u00e9es pour \u00e9viter, pr\u00e9venir ou r\u00e9duire les incidences n\u00e9gatives notables probables sur l\u2019environnement, et si possible, compenser les effets n\u00e9gatifs notables probables sur l\u2019environnement;<\/em><\/p>\n<p><em>4\u00b0 une description des solutions de substitution raisonnables qui ont \u00e9t\u00e9 examin\u00e9es par le demandeur, en fonction du projet et de ses caract\u00e9ristiques sp\u00e9cifiques, et une indication des principales raisons du choix de ce dernier, eu \u00e9gard aux effets du projet sur l\u2019environnement;<\/em><\/p>\n<p><em>5\u00b0 un r\u00e9sum\u00e9 non technique des points 1\u00b0 \u00e0 4\u00b0 mentionn\u00e9s ci-dessus;<\/em><\/p>\n<p><em>6\u00b0 toute information suppl\u00e9mentaire pr\u00e9cis\u00e9e par le Gouvernement, en fonction des caract\u00e9ristiques sp\u00e9cifiques d\u2019un projet ou d\u2019un type de projets particulier et des \u00e9l\u00e9ments de l\u2019environnement sur lesquels une incidence pourrait se produire.<\/em><\/p>\n<p><em>Lorsque le projet concerne une installation ou une activit\u00e9 reprise sur la liste vis\u00e9e \u00e0 l\u2019annexe 3 du d\u00e9cret du 5 d\u00e9cembre 2008 relatif \u00e0 la gestion des sols, la description du projet vis\u00e9e au paragraphe 2, 1\u00b0, comporte en tout cas :<\/em><\/p>\n<p><em>1\u00b0 des renseignements g\u00e9n\u00e9raux et notamment les donn\u00e9es \u00e9ventuelles relatives au terrain concern\u00e9 reprises dans la banque de donn\u00e9es de l\u2019\u00e9tat des sols vis\u00e9e \u00e0 l\u2019article 10 du d\u00e9cret du 5 d\u00e9cembre 2008 relatif \u00e0 la gestion des sols et les valeurs applicables, en ce compris les concentrations de fond au sens du m\u00eame d\u00e9cret;<\/em><\/p>\n<p><em>2\u00b0 un historique du site et, le cas \u00e9ch\u00e9ant, de l\u2019exploitation en cours;<\/em><\/p>\n<p><em>3\u00b0 des renseignements g\u00e9ologiques, hydrologiques et hydrog\u00e9ologiques.<\/em><\/p>\n<ul>\n<li><em> 2. Le Gouvernement peut arr\u00eater les formes et compl\u00e9ter le contenu minimal de l\u2019\u00e9tude d\u2019incidences sur l\u2019environnement.<\/em><\/li>\n<li><em> 3. Pour \u00e9viter tout double emploi lors des \u00e9valuations, l\u2019auteur de l\u2019\u00e9tude d\u2019incidences tient compte, le cas \u00e9ch\u00e9ant, dans l\u2019\u00e9laboration de l\u2019\u00e9tude d\u2019incidences sur l\u2019environnement, pour autant qu\u2019ils soient pertinents ou actuels, des r\u00e9sultats disponibles d\u2019autres \u00e9valuations pertinentes. Ceux-ci sont identifi\u00e9s comme tels dans l\u2019\u00e9tude d\u2019incidences.<\/em><\/li>\n<li><em> 4. Si un avis est rendu en vertu de l\u2019article D.69, l\u2019\u00e9tude d\u2019incidences est fond\u00e9e sur cet avis et inclut les informations qui peuvent raisonnablement \u00eatre requises pour arriver \u00e0 une conclusion motiv\u00e9e sur les incidences notables du projet sur l\u2019environnement, compte tenu des connaissances et des m\u00e9thodes d\u2019\u00e9valuation existantes.<strong>]<\/strong><\/em><br \/><em>(1)<strong>[D\u00e9cret 10.11.2006] \u2013\u00a0<\/strong>(2)<strong>[D\u00e9cret 05.12.2008]<\/strong>\u2013 (3)<strong>[D\u00e9cret 24.05.2018]\u00a0\u00bb<\/strong><\/em><\/li>\n<\/ul>\n<p>Le conseil d\u2019\u00e9tat enseigne:<\/p>\n<p><em>\u00ab\u00a0L\u2019\u00e9tude d\u2019incidences a pour objectif d\u2019identifier, d\u00e9crire et \u00e9valuer de<\/em><br \/><em>mani\u00e8re appropri\u00e9e, en fonction de chaque cas particulier, les effets directs et<\/em><br \/><em>indirects, synergiques ou cumulatifs, \u00e0 court, moyen et long termes, permanents et<\/em><br \/><em>temporaires, d\u2019un projet sur l\u2019environnement, et de pr\u00e9senter et \u00e9valuer les mesures<\/em><br \/><em>envisag\u00e9es pour \u00e9viter, r\u00e9duire les effets n\u00e9gatifs du projet sur l\u2019environnement et, si<\/em><br \/><em>possible, y rem\u00e9dier. Elle vise \u00e0 informer non seulement le public de toutes les<\/em><br \/><em>incidences environnementales d\u2019un projet afin de lui permettre de faire valoir<\/em><br \/><em>utilement ses observations, mais \u00e9galement l\u2019autorit\u00e9 comp\u00e9tente afin de lui<\/em><br \/><em>permettre de statuer en toute connaissance de ces incidences. \u00c0 cette fin, l\u2019\u00e9tude doit<\/em><br \/><em>\u00eatre compl\u00e8te, en ce sens qu\u2019elle doit constituer une \u00e9valuation globale et compl\u00e8te<\/em><br \/><em>de l\u2019ensemble des incidences environnementales du projet consid\u00e9r\u00e9.\u00a0\u00bb (CE, 247.547, Cimenteries CBR du 14 mai 2020, p. 23)<\/em><\/p>\n<p>Face \u00e0 une \u00e9tude d\u2019incidences sur l\u2019environnement lacunaire, le conseil d\u2019\u00e9tat enseigne\u00a0 quant \u00e0 l\u2019autorit\u00e9:<\/p>\n<p><em>\u00ab\u00a0L\u2019autorit\u00e9 exprime ainsi l\u2019existence d\u2019un doute \u00e0 cet \u00e9gard, que l\u2019\u00e9tude<\/em><br \/><em>d\u2019incidences ne permet pas de lever \u00e9tant donn\u00e9 qu\u2019elle n\u2019a pas int\u00e9gr\u00e9 ce param\u00e8tre<\/em><br \/><em>dans ses simulations. La circonstance que certains tron\u00e7ons de la bande<\/em><br \/><em>transporteuse soient en partie couverts ne permet pas d\u2019\u00e9carter le doute exprim\u00e9 par<\/em><br \/><em>l\u2019autorit\u00e9, et n\u2019est pas de nature \u00e0 entacher d\u2019erreur l\u2019appr\u00e9ciation port\u00e9e par elle sur<\/em><br \/><em>cette question, l\u2019\u00e9tude d\u2019incidences ne fournissant en effet aucun renseignement<\/em><br \/><em>quant \u00e0 la nature du mat\u00e9riau de couverture des bandes et sa capacit\u00e9 \u00e0 couvrir, le<\/em><br \/><em>cas \u00e9ch\u00e9ant, le bruit g\u00e9n\u00e9r\u00e9 par ce type d\u2019installations.<\/em><br \/><em>11. L\u2019auteur de l\u2019acte attaqu\u00e9 ajoute qu\u2019il ressort d\u2019un autre dossier que la<\/em><br \/><em>prise en compte des \u00e9missions sonores des bandes transporteuses n\u2019est pas un<\/em><br \/><em>\u00e9l\u00e9ment complexe \u00e0 g\u00e9rer. Ce faisant, il expose la raison suppl\u00e9mentaire pour<\/em><br \/><em>laquelle il estime ne pas \u00eatre en mesure de se prononcer en toute connaissance de<\/em><br \/><em>cause et ne pas pouvoir \u00e9carter les risques de nuisances sonores d\u00e9nonc\u00e9s dans un<\/em><br \/><em>des recours administratifs dont il \u00e9tait saisi.\u00a0\u00bb(CE, 247.547, Cimenteries CBR du 14 mai 2020, p. 22)<\/em><\/p>\n<p>Face \u00e0 une \u00e9tude d\u2019incidence sur l\u2019environnement lacunaire, le conseil d\u2019\u00e9tat enseigne encore quant aux r\u00e9clamants:<\/p>\n<p><em>\u00ab\u00a0Par ces motifs, l\u2019auteur de l\u2019acte attaqu\u00e9 consid\u00e8re que si l\u2019opinion<\/em><br \/><em>d\u2019une instance d\u2019avis peut \u00e9clairer l\u2019autorit\u00e9 en charge d\u2019une demande de permis, il<\/em><br \/><em>n\u2019est pas acceptable que cette instance pallie les manquements d\u2019une \u00e9tude<\/em><br \/><em>d\u2019incidences en ce sens qu\u2019elle ne peut fournir \u00e0 l\u2019autorit\u00e9 des informations et<\/em><br \/><em>imposer des conditions qui auraient d\u00fb se trouver dans l\u2019\u00e9tude d\u2019incidences et, donc<\/em><br \/><em>\u00eatre port\u00e9es \u00e0 la connaissance du public,\u00a0<strong>l\u2019objectif de l\u2019\u00e9tude \u00e9tant notamment<\/strong><\/em><br \/><strong><em>d\u2019informer le public de tous les aspects du dossier en mati\u00e8re d\u2019\u00e9missions de<\/em><\/strong><br \/><strong><em>poussi\u00e8res, afin de lui permettre de formuler des observations en toute connaissance<\/em><\/strong><br \/><strong><em>de cause.<\/em><\/strong><br \/><em>En consid\u00e9rant que l\u2019\u00e9tude d\u2019incidences n\u2019a pas rencontr\u00e9 cet objectif, le<\/em><br \/><em>fonctionnaire technique et l\u2019auteur de l\u2019acte attaqu\u00e9 ne commettent pas d\u2019erreur<\/em><br \/><em>puisque l\u2019AWAC rel\u00e8ve elle-m\u00eame dans son avis que ni l\u2019\u00e9valuation de la situation<\/em><br \/><em>initiale, ni l\u2019\u00e9valuation de la situation projet\u00e9e ne contiennent la moindre<\/em><br \/><em>quantification des \u00e9missions de poussi\u00e8res et de particules fines, ni d\u2019estimation de<\/em><br \/><em>l\u2019impact du projet sur le voisinage.\u00a0<strong>Partant, le public n\u2019a pas \u00e9t\u00e9 en mesure de<\/strong><\/em><br \/><strong><em>formuler en toute connaissance de cause des observations<\/em><\/strong><em>\u00a0\u00e0 cet \u00e9gard, et notamment<\/em><br \/><em>au sujet de l\u2019ad\u00e9quation des mesures et recommandations sugg\u00e9r\u00e9es dans la<\/em><br \/><em>demande, dans l\u2019\u00e9tude d\u2019incidences et dans les avis de l\u2019AWAC pour limiter ces<\/em><br \/><em>nuisances.\u00a0\u00bb (CE, 247.547, Cimenteries CBR du 14 mai 2020, p. 26)<\/em><\/p>\n<p><span style=\"text-decoration: underline;\">2.4.2\/ En ce qui concerne les conditions impos\u00e9es par les instances d&rsquo;avis en vue de pallier les insuffisances de l&rsquo;EIE<\/span><\/p>\n<p>Le rapport du fonctionnaire technique sur recours dans l&rsquo;affaire de la carri\u00e8re de Bosism\u00e9 indique:<\/p>\n<p><strong><em>C<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>i<\/em><em>d<\/em><em>\u00e9<\/em><em>r<\/em><em>a<\/em><em>n<\/em><em>t <\/em><em>q<\/em><em>u<\/em><em>e \u00a0c<\/em><em>e<\/em><em>tt<\/em><em>e <\/em><em>li<\/em><em>s<\/em><em>t<\/em><em>e d<\/em><em>e <\/em><em>m<\/em><em>a<\/em><em>n<\/em><em>qu<\/em><em>e<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>s <\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>f<\/em><em>i<\/em><em>r<\/em><em>m<\/em><em>e <\/em><em>q<\/em><em>u<\/em><em>e\u00a0 l<\/em><em>e <\/em><em>p<\/em><em>u<\/em><em>b<\/em><em>l<\/em><em>i<\/em><em>c<\/em><em>, \u00a0<\/em><em>a<\/em><em>u <\/em><em>s<\/em><em>e<\/em><em>n<\/em><em>s <\/em><em>l<\/em><em>a<\/em><em>r<\/em><em>g<\/em><em>e \u00a0<\/em><em>(<\/em><em>pa<\/em><em>s\u00a0\u00a0 <\/em><em>u<\/em><em>n<\/em><em>i<\/em><em>q<\/em><em>u<\/em><em>e<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t \u00a0<\/em><em>l<\/em><em>e<\/em><em>s \u00a0r<\/em><em>e<\/em><em>q<\/em><em>u<\/em><em>\u00e9<\/em><em>r<\/em><em>a<\/em><em>n<\/em><em>t<\/em><em>s \u00a0<\/em><em>m<\/em><em>a<\/em><em>i<\/em><em>s \u00a0<\/em><em>t<\/em><em>o<\/em><em>u<\/em><em>t<\/em><em>e \u00a0<\/em><em>p<\/em><em>e<\/em><em>r<\/em><em>s<\/em><em>o<\/em><em>n<\/em><em>n<\/em><em>e \u00a0<\/em><em>q<\/em><em>u<\/em><em>i <\/em><em>a \u00a0<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>u<\/em><em>l<\/em><em>t<\/em><em>\u00e9 <\/em><em>l<\/em><em>&lsquo;<\/em><em>E<\/em><em>I<\/em><em>E<\/em><em> \u00a0lor<\/em><em>s<\/em><em> \u00a0de \u00a0<\/em><em>l<\/em><em>&lsquo;<\/em><em>e<\/em><em>nq<\/em><em>u<\/em><em>\u00ea<\/em><em>t<\/em><em>e<\/em><em> \u00a0<\/em><em>pub<\/em><em>l<\/em><em>i<\/em><em>qu<\/em><em>e<\/em><em>) \u00a0<\/em><em>n<\/em><em>&lsquo;<\/em><em>a <\/em><em>p<\/em><em>a<\/em><em>s \u00a0<\/em><em>p<\/em><em>u \u00a0<\/em><em>\u00ea<\/em><em>t<\/em><em>r<\/em><em>e<\/em><em> \u00a0<\/em><em>i<\/em><em>n<\/em><em>f<\/em><em>o<\/em><em>r<\/em><em>m<\/em><em>\u00e9<\/em><em> \u00a0<\/em><\/strong><em>d<\/em><em>e \u00a0<\/em><em>to<\/em><em>u<\/em><em>s <\/em><em>l<\/em><em>e<\/em><em>s a<\/em><em>s<\/em><em>p<\/em><em>e<\/em><em>c<\/em><em>t<\/em><em>s <\/em><em>d<\/em><em>u\u00a0 \u00a0do<\/em><em>ss<\/em><em>ie<\/em><em>r \u00a0<\/em><em>e<\/em><em>n\u00a0 \u00a0mati<\/em><em>\u00e8<\/em><em>r<\/em><em>e\u00a0 \u00a0<\/em><em>d<\/em><em>&lsquo;<\/em><em>\u00e9<\/em><em>m<\/em><em>i<\/em><em>s<\/em><em>s<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>s \u00a0<\/em><em>d<\/em><em>e \u00a0<\/em><em>p<\/em><em>ou<\/em><em>s<\/em><em>s<\/em><em>i<\/em><em>\u00e8<\/em><em>r<\/em><em>e<\/em><em>s<\/em><em>,\u00a0 \u00a0<\/em><em>d<\/em><em>u\u00a0 \u00a0<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>t<\/em><em>r<\/em><em>\u00f4l<\/em><em>e\u00a0\u00a0 <\/em><em>d<\/em><em>e\u00a0 \u00a0<\/em><em>l<\/em><em>e<\/em><em>u<\/em><em>r<\/em><em>s <\/em><em>r<\/em><em>e<\/em><em>t<\/em><em>o<\/em><em>m<\/em><em>b<\/em><em>\u00e9e<\/em><em>s<\/em><em> \u00a0e<\/em><em>t <\/em><em>d<\/em><em>e<\/em><em>s \u00a0moyen<\/em><em>s \u00a0\u00e9<\/em><em>v<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>u<\/em><em>e<\/em><em>ll<\/em><em>e<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em> \u00a0mi<\/em><em>s\u00a0<\/em><em>a<\/em><em>l<\/em><em>o<\/em><em>r<\/em><em>s\u00a0\u00a0 <\/em><em>q<\/em><em>u<\/em><em>&lsquo;i<\/em><em>l \u00a0<\/em><em>s<\/em><em>&lsquo;<\/em><em>a<\/em><em>g<\/em><em>i<\/em><em>t \u00a0<\/em><em>d<\/em><em>&lsquo;<\/em><em>u<\/em><em>n\u00a0 \u00a0<\/em><em>s<\/em><em>u<\/em><em>j<\/em><em>e<\/em><em>t \u00a0<\/em><em>p<\/em><em>ou<\/em><em>r<\/em><em>t<\/em><em>an<\/em><em>t \u00a0<\/em><em>\u00e9<\/em><em>m<\/em><em>i<\/em><em>n<\/em><em>e<\/em><em>m<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t \u00a0<\/em><em>p<\/em><em>r<\/em><em>\u00e9<\/em><em>o<\/em><em>c<\/em><em>c<\/em><em>u<\/em><em>p<\/em><em>a<\/em><em>n<\/em><em>t \u00a0<\/em><em>po<\/em><em>u<\/em><em>r \u00a0<\/em><em>l<\/em><em>e<\/em><em>u<\/em><em>r <\/em><em>b<\/em><em>i<\/em><em>e<\/em><em>n<\/em><em>&#8211;<\/em><em>\u00ea<\/em><em>t<\/em><em>r<\/em><em>e<\/em><em> \u00a0;<\/em><\/p>\n<p><em>C<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>i<\/em><em>d<\/em><em>\u00e9<\/em><em>r<\/em><em>an<\/em><em>t \u00a0<\/em><em>q<\/em><em>u<\/em><em>e<\/em><em>,\u00a0 \u00a0<\/em><em>l<\/em><em>a \u00a0<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>u<\/em><em>l<\/em><em>t<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n \u00a0<\/em><em>d<\/em><em>u \u00a0do<\/em><em>s<\/em><em>s<\/em><em>i<\/em><em>e<\/em><em>r\u00a0 <\/em><em>d<\/em><em>e \u00a0demand<\/em><em>e \u00a0<\/em><em>s<\/em><em>e \u00a0<\/em><em>f<\/em><em>a<\/em><em>i<\/em><em>s<\/em><em>a<\/em><em>n<\/em><em>t \u00a0<\/em><em>l<\/em><em>o<\/em><em>r<\/em><em>s \u00a0<\/em><em>d<\/em><em>e <\/em><em>l<\/em><em>&lsquo;<\/em><em>e<\/em><em>n<\/em><em>q<\/em><em>u<\/em><em>\u00ea<\/em><em>t<\/em><em>e\u00a0 \u00a0<\/em><em>p<\/em><em>u<\/em><em>b<\/em><em>l<\/em><em>i<\/em><em>q<\/em><em>u<\/em><em>e<\/em><em>,\u00a0\u00a0 \u00a0<\/em><em>e<\/em><em>t\u00a0 \u00a0<\/em><em>d<\/em><em>o<\/em><em>n<\/em><em>c<\/em><em>,\u00a0\u00a0 \u00a0<\/em><em>a\u00a0 \u00a0fortiori<\/em><em>,\u00a0\u00a0\u00a0 <\/em><em>a<\/em><em>v<\/em><em>a<\/em><em>n<\/em><em>t\u00a0 \u00a0<\/em><em>l<\/em><em>a\u00a0 \u00a0<\/em><em>d<\/em><em>\u00e9<\/em><em>c<\/em><em>i<\/em><em>s<\/em><em>i<\/em><em>o<\/em><em>n\u00a0 \u00a0<\/em><em>d<\/em><em>e\u00a0 \u00a0<\/em><em>l<\/em><em>&lsquo;<\/em><em>a<\/em><em>u<\/em><em>t<\/em><em>o<\/em><em>r<\/em><em>i<\/em><em>t<\/em><em>\u00e9 c<\/em><em>o<\/em><em>m<\/em><em>p<\/em><em>\u00e9<\/em><em>t<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>e \u00a0<\/em><em>e<\/em><em>n \u00a0prem<\/em><em>i<\/em><em>\u00e8<\/em><em>r<\/em><em>e \u00a0<\/em><em>i<\/em><em>n<\/em><em>s<\/em><em>t<\/em><em>a<\/em><em>n<\/em><em>c<\/em><em>e<\/em><em>, \u00a0<\/em><em>i<\/em><em>l \u00a0le<\/em><em>u<\/em><em>r \u00a0\u00e9<\/em><em>t<\/em><em>a<\/em><em>i<\/em><em>t\u00a0 <\/em><em>i<\/em><em>m<\/em><em>p<\/em><em>o<\/em><em>ss<\/em><em>i<\/em><em>b<\/em><em>l<\/em><em>e \u00a0<\/em><em>d<\/em><em>e \u00a0s<\/em><em>a<\/em><em>vo<\/em><em>i<\/em><em>r <\/em><em>q<\/em><em>u<\/em><em>e \u00a0l<\/em><em>e<\/em><em>s <\/em><em>n<\/em><em>o<\/em><em>m<\/em><em>b<\/em><em>r<\/em><em>e<\/em><em>u<\/em><em>s<\/em><em>e<\/em><em>s\u00a0\u00a0 \u00a0<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>d<\/em><em>i<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>s\u00a0\u00a0 \u00a0<\/em><em>q<\/em><em>u<\/em><em>i\u00a0 \u00a0<\/em><em>p<\/em><em>o<\/em><em>u<\/em><em>v<\/em><em>a<\/em><em>i<\/em><em>e<\/em><em>n<\/em><em>t\u00a0\u00a0 \u00a0\u00ea<\/em><em>t<\/em><em>r<\/em><em>e\u00a0\u00a0 \u00a0<\/em><em>i<\/em><em>m<\/em><em>p<\/em><em>o<\/em><em>s<\/em><em>\u00e9e<\/em><em>s\u00a0\u00a0 \u00a0<\/em><em>d<\/em><em>a<\/em><em>n<\/em><em>s\u00a0\u00a0\u00a0\u00a0 <\/em><em>l<\/em><em>e\u00a0\u00a0 \u00a0<\/em><em>p<\/em><em>e<\/em><em>r<\/em><em>m<\/em><em>i<\/em><em>s <\/em><em>f<\/em><em>i<\/em><em>n<\/em><em>a<\/em><em>l<\/em><em>e<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em> \u00a0<\/em><em>d<\/em><em>\u00e9<\/em><em>l<\/em><em>i<\/em><em>v<\/em><em>r<\/em><em>\u00e9<\/em><em> \u00a0<\/em><em>po<\/em><em>u<\/em><em>v<\/em><em>a<\/em><em>i<\/em><em>e<\/em><em>n<\/em><em>t<\/em> <em>p<\/em><em>a<\/em><em>l<\/em><em>i<\/em><em>e<\/em><em>r<\/em><em> \u00a0toutes \u00a0ces i<\/em><em>n<\/em><em>c<\/em><em>o<\/em><em>nnu<\/em><em>e<\/em><em>s ;<\/em><\/p>\n<p><em>C<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>i<\/em><em>d<\/em><em>\u00e9<\/em><em>r<\/em><em>an<\/em><em>t<\/em><em>,<\/em><em> \u00a0<\/em><em>d<\/em><em>\u00e8<\/em><em>s \u00a0<\/em><em>l<\/em><em>o<\/em><em>r<\/em><em>s<\/em><em>,<\/em><em> \u00a0<\/em><em>q<\/em><em>u<\/em><em>e \u00a0s<\/em><em>u<\/em><em>r<\/em><em> \u00a0ce poi<\/em><em>n<\/em><em>t<\/em><em>,<\/em><em> \u00a0<\/em><em>l<\/em><em>&lsquo;<\/em><em>\u00e9<\/em><em>t<\/em><em>u<\/em><em>d<\/em><em>e<\/em><em> \u00a0<\/em><em>d<\/em><em>&lsquo;<\/em><em>i<\/em><em>n<\/em><em>c<\/em><em>i<\/em><em>d<\/em><em>e<\/em><em>n<\/em><em>c<\/em><em>e \u00a0<\/em><em>n<\/em><em>&lsquo;<\/em><em>a <\/em><em>pa<\/em><em>s \u00a0re<\/em><em>n<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>t<\/em><em>r<\/em><em>\u00e9 <\/em><em>s<\/em><em>o<\/em><em>n \u00a0ob<\/em><em>j<\/em><em>e<\/em><em>c<\/em><em>t<\/em><em>i<\/em><em>f<\/em> <em>n<\/em><em>o<\/em><em>n<\/em><em>o<\/em><em>b<\/em><em>s<\/em><em>t<\/em><em>an<\/em><em>t<\/em><em> \u00a0<\/em><em>l<\/em><em>e \u00a0f<\/em><em>a<\/em><em>i<\/em><em>t<\/em><em> \u00a0que \u00a0l<\/em><em>&lsquo;<\/em><em>A<\/em><em>W<\/em><em>A<\/em><em>C<\/em><em> \u00a0re<\/em><em>m<\/em><em>e<\/em><em>t<\/em><em> \u00a0<\/em><em>f<\/em><em>i<\/em><em>n<\/em><em>a<\/em><em>l<\/em><em>e<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em> \u00a0u<\/em><em>n \u00a0<\/em><em>av<\/em><em>i<\/em><em>s \u00a0<\/em><em>f<\/em><em>a<\/em><em>v<\/em><em>o<\/em><em>r<\/em><em>a<\/em><em>b<\/em><em>l<\/em><em>e <\/em><em>e<\/em><em>n \u00a0<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>f<\/em><em>i<\/em><em>r<\/em><em>m<\/em><em>a<\/em><em>n<\/em><em>t<\/em><em> \u00a0l<\/em><em>a <\/em><em>p<\/em><em>a<\/em><em>n<\/em><em>o<\/em><em>p<\/em><em>l<\/em><em>i<\/em><em>e<\/em><em> \u00a0<\/em><em>d<\/em><em>e co<\/em><em>nd<\/em><em>i<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>s \u00a0i<\/em><em>m<\/em><em>p<\/em><em>o<\/em><em>s<\/em><em>\u00e9<\/em><em>e<\/em><em>s <\/em><em>d<\/em><em>a<\/em><em>n<\/em><em>s \u00a0<\/em><em>l<\/em><em>e <\/em><em>p<\/em><em>e<\/em><em>r<\/em><em>m<\/em><em>i<\/em><em>s<\/em><em> \u00a0;<\/em><\/p>\n<p><strong><em>C<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>i<\/em><em>d<\/em><em>\u00e9<\/em><em>r<\/em><em>a<\/em><em>n<\/em><em>t <\/em><em>q<\/em><em>u<\/em><em>&lsquo;<\/em><em>i<\/em><em>l <\/em><em>n<\/em><em>&lsquo;<\/em><em>e<\/em><em>s<\/em><em>t <\/em><em>pa<\/em><em>s \u00a0<\/em><em>a<\/em><em>c<\/em><em>c<\/em><em>e<\/em><em>p<\/em><em>t<\/em><em>a<\/em><em>b<\/em><em>l<\/em><em>e <\/em><em>q<\/em><em>u<\/em><em>&lsquo;<\/em><em>u<\/em><em>n<\/em><em>e <\/em><em>i<\/em><em>n<\/em><em>s<\/em><em>t<\/em><em>a<\/em><em>n<\/em><em>c<\/em><em>e <\/em><em>d<\/em><em>&lsquo;<\/em><em>a<\/em><em>v<\/em><em>i<\/em><em>s <\/em><em>p<\/em><em>a<\/em><em>l<\/em><em>l<\/em><em>i<\/em><em>e <\/em><em>l<\/em><em>e<\/em><em>s <\/em><em>m<\/em><em>a<\/em><em>nqu<\/em><em>e<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>s <\/em><em>d&rsquo;<\/em><em>u<\/em><em>n<\/em><em>e <\/em><em>E<\/em><em>I<\/em><\/strong><em><strong>E<\/strong>, <\/em><em>c<\/em><em>e <\/em><em>q<\/em><em>u<\/em><em>e <\/em><em>I<\/em><em>&lsquo;<\/em><em>A<\/em><em>W<\/em><em>A<\/em><em>C c<\/em><em>o<\/em><em>n<\/em><em>fi<\/em><em>r<\/em><em>m<\/em><em>e <\/em><em>po<\/em><em>u<\/em><em>rt<\/em><em>an<\/em><em>t <\/em><em>e<\/em><em>n <\/em><em>s<\/em><em>o<\/em><em>n avis <\/em><em>e<\/em><em>n m<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>n<\/em><em>a<\/em><em>n<\/em><em>t \u00a0<\/em><em>:\u00a0 \u00a0<\/em>\u00ab\u00a0Malgr\u00e9 \u00a0les \u00a0lacunes de \u00a0l&rsquo;EIE, \u00a0l&rsquo;AwAC conna\u00eet \u00a0et a \u00a0pris\u00a0 en compte \u00a0la probl\u00e9matique \u00a0des \u00a0particules \u00a0fines \u00a0dans \u00a0son \u00a0avis en \u00a0premi\u00e8re \u00a0instance. \u00a0Si \u00a0rien \u00a0n&rsquo;est\u00a0entrepris,\u00a0 \u00a0il\u00a0 \u00a0faut \u00a0effectivement \u00a0s&rsquo;attendre\u00a0 \u00a0\u00e0 \u00a0des \u00a0nuisances \u00a0(retomb\u00e9es)\u00a0 \u00a0et \u00a0\u00e0 \u00a0une\u00a0pollution \u00a0de \u00a0l&rsquo;air\u00a0 accrue \u00a0comme\u00a0 \u00a0\u00e0 \u00a0proximit\u00e9 \u00a0de \u00a0nombreuses \u00a0carri\u00e8res \u00a0wallonnes. L&rsquo;imposition \u00a0d&rsquo;un \u00a0PRED \u00a0et \u00a0les \u00a0autres \u00a0impositions \u00a0du \u00a0permis visent \u00e0 limiter \u00a0fortement\u00a0les \u00a0\u00e9missions de poussi\u00e8res et de particules fines.\u00a0\u00bb; \u00a0<em>q<\/em><em>u<\/em><em>e<\/em><em>, \u00a0<\/em><em>d<\/em><em>&lsquo;<\/em><em>un<\/em><em>e <\/em><em>m<\/em><em>a<\/em><em>n<\/em><em>i<\/em><em>\u00e8<\/em><em>r<\/em><em>e<\/em><em> \u00a0g\u00e9<\/em><em>n<\/em><em>\u00e9<\/em><em>r<\/em><em>ale<\/em><em>, <\/em><em>d<\/em><em>e<\/em><em>s\u00a0 \u00a0c<\/em><em>o<\/em><em>n<\/em><em>d<\/em><em>i<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>s\u00a0 \u00a0<\/em><em>d<\/em><em>&lsquo;<\/em><em>e<\/em><em>x<\/em><em>p<\/em><em>l<\/em><em>o<\/em><em>i<\/em><em>t<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n\u00a0 \u00a0<\/em><em>so<\/em><em>n<\/em><em>t \u00a0<\/em><em>i<\/em><em>m<\/em><em>p<\/em><em>o<\/em><em>s\u00e9<\/em><em>e<\/em><em>s <\/em><em>pou<\/em><em>r \u00a0<\/em><em>l<\/em><em>i<\/em><em>m<\/em><em>i<\/em><em>t<\/em><em>e<\/em><em>r\u00a0\u00a0 <\/em><em>\u00e0\u00a0 \u00a0un\u00a0 \u00a0niv<\/em><em>e<\/em><em>a<\/em><em>u <\/em><em>a<\/em><em>c<\/em><em>c<\/em><em>e<\/em><em>p<\/em><em>t<\/em><em>a<\/em><em>b<\/em><em>l<\/em><em>e\u00a0\u00a0 les\u00a0 \u00a0<\/em><em>nu<\/em><em>i<\/em><em>s<\/em><em>a<\/em><em>n<\/em><em>c<\/em><em>e<\/em><em>s \u00a0<\/em><em>i<\/em><em>d<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>i<\/em><em>f<\/em><em>i<\/em><em>\u00e9e<\/em><em>s \u00a0<\/em><em>p<\/em><em>a<\/em><em>r \u00a0<\/em><em>l<\/em><em>&lsquo;<\/em><em>E<\/em><em>I<\/em><em>E \u00a0<\/em><em>;\u00a0 \u00a0<\/em><em>q<\/em><em>u<\/em><em>&lsquo;<\/em><em>e<\/em><em>l<\/em><em>le<\/em><em>s \u00a0<\/em><em>n<\/em><em>&lsquo;<\/em><em>o<\/em><em>n<\/em><em>t \u00a0<\/em><em>pa<\/em><em>s\u00a0 \u00a0<\/em><em>p<\/em><em>o<\/em><em>u<\/em><em>r <\/em><em>v<\/em><em>o<\/em><em>c<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em> \u00a0d<\/em><em>e c<\/em><em>o<\/em><em>m<\/em><em>p<\/em><em>e<\/em><em>n<\/em><em>s<\/em><em>e<\/em><em>r<\/em> <em>u<\/em><em>n<\/em><em>e <\/em><em>a<\/em><em>n<\/em><em>a<\/em><em>l<\/em><em>y<\/em><em>s<\/em><em>e \u00a0<\/em><em>d<\/em><em>\u00e9<\/em><em>f<\/em><em>i<\/em><em>c<\/em><em>i<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>e<\/em><em> \u00a0<\/em><em>a<\/em><em>u n<\/em><em>i<\/em><em>v<\/em><em>e<\/em><em>a<\/em><em>u<\/em><em> \u00a0d<\/em><em>e <\/em><em>l<\/em><em>&lsquo;<\/em><em>E<\/em><em>I<\/em><em>E<\/em><em>;<\/em><\/p>\n<p><em>C<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>i<\/em><em>d<\/em><em>\u00e9<\/em><em>r<\/em><em>a<\/em><em>n<\/em><em>t <\/em><em>q<\/em><em>u<\/em><em>e <\/em><em>l<\/em><em>e<\/em><em>s <\/em><em>po<\/em><em>i<\/em><em>n<\/em><em>t<\/em><em>s <\/em><em>a<\/em><em>b<\/em><em>o<\/em><em>r<\/em><em>d<\/em><em>\u00e9<\/em><em>s <\/em><em>c<\/em><em>i<\/em><em>&#8211;<\/em><em>d<\/em><em>e<\/em><em>ss<\/em><em>u<\/em><em>s <\/em><em>d<\/em><em>a<\/em><em>n<\/em><em>s <\/em><em>l<\/em><em>&lsquo;<\/em><em>av<\/em><em>i<\/em><em>s <\/em><em>d<\/em><em>u Fon<\/em><em>c<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>n<\/em><em>a<\/em><em>i<\/em><em>r<\/em><em>e <\/em><em>t<\/em><em>e<\/em><em>c<\/em><em>h<\/em><em>n<\/em><em>i<\/em><em>q<\/em><em>u<\/em><em>e \u00a0c<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>t<\/em><em>i<\/em><em>t<\/em><em>u<\/em><em>e<\/em><em>n<\/em><em>t \u00a0<\/em><em>l<\/em><em>&lsquo;<\/em><em>e<\/em><em>s<\/em><em>s<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em>i<\/em><em>e<\/em><em>l \u00a0<\/em><em>d<\/em><em>e<\/em><em>s \u00a0probl\u00e9<\/em><em>m<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>q<\/em><em>u<\/em><em>e<\/em><em>s \u00a0<\/em><em>r<\/em><em>e<\/em><em>n<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>t<\/em><em>r<\/em><em>\u00e9e<\/em><em>s \u00a0<\/em><em>da<\/em><em>n<\/em><em>s\u00a0\u00a0 ce <\/em><em>d<\/em><em>o<\/em><em>s<\/em><em>s<\/em><em>i<\/em><em>e<\/em><em>r<\/em><em>; <\/em><em>q<\/em><em>u<\/em><em>e <\/em><em>b<\/em><em>o<\/em><em>n nomb<\/em><em>r<\/em><em>e <\/em><em>d<\/em><em>&lsquo;<\/em><em>a<\/em><em>u<\/em><em>t<\/em><em>r<\/em><em>e<\/em><em>s <\/em><em>po<\/em><em>i<\/em><em>n<\/em><em>t<\/em><em>s <\/em><em>p<\/em><em>l<\/em><em>u<\/em><em>s <\/em><em>s<\/em><em>e<\/em><em>c<\/em><em>o<\/em><em>nd<\/em><em>a<\/em><em>ir<\/em><em>e<\/em><em>s<\/em><em>, <\/em><em>v<\/em><em>o<\/em><em>ir<\/em><em>e <\/em><em>p<\/em><em>a<\/em><em>rf<\/em><em>oi<\/em><em>s <\/em><em>a<\/em><em>n<\/em><em>ec<\/em><em>d<\/em><em>o<\/em><em>t<\/em><em>i<\/em><em>q<\/em><em>u<\/em><em>e<\/em><em>s<\/em><em>, <\/em><em>s<\/em><em>o<\/em><em>n<\/em><em>t <\/em><em>s<\/em><em>o<\/em><em>u<\/em><em>l<\/em><em>e<\/em><em>v<\/em><em>\u00e9<\/em><em>s <\/em><em>p<\/em><em>a<\/em><em>r <\/em><em>l<\/em><em>e<\/em><em>s requ\u00e9ra<\/em><em>n<\/em><em>t<\/em><em>s<\/em><em>; <\/em><em>q<\/em><em>u<\/em><em>&lsquo;<\/em><em>i<\/em><em>l <\/em><em>e<\/em><em>s<\/em><em>t <\/em><em>t<\/em><em>o<\/em><em>u<\/em><em>t<\/em><em>e<\/em><em>f<\/em><em>o<\/em><em>i<\/em><em>s <\/em><em>d<\/em><em>i<\/em><em>ff<\/em><em>i<\/em><em>ci<\/em><em>l<\/em><em>e<\/em><em>,\u00a0 <\/em><em>e<\/em><em>u <\/em><em>\u00e9<\/em><em>ga<\/em><em>r<\/em><em>d<\/em><em> \u00a0au \u00a0t<\/em><em>e<\/em><em>m<\/em><em>p<\/em><em>s <\/em><em>q<\/em><em>u<\/em><em>e \u00a0<\/em><em>p<\/em><em>e<\/em><em>uv<\/em><em>e<\/em><em>n<\/em><em>t<\/em><em> \u00a0<\/em><em>c<\/em><em>o<\/em><em>n<\/em><em>s<\/em><em>a<\/em><em>c<\/em><em>r<\/em><em>e<\/em><em>r<\/em><em> \u00a0les s<\/em><em>e<\/em><em>rvi<\/em><em>c<\/em><em>e<\/em><em>s <\/em><em>d<\/em><em>e \u00a0<\/em><em>r<\/em><em>e<\/em><em>c<\/em><em>o<\/em><em>u<\/em><em>r<\/em><em>s<\/em><em> \u00a0\u00e0 ce <\/em><em>d<\/em><em>o<\/em><em>ss<\/em><em>i<\/em><em>e<\/em><em>r <\/em><em>p<\/em><em>a<\/em><em>r\u00a0 \u00a0<\/em><em>r<\/em><em>a<\/em><em>pp<\/em><em>o<\/em><em>rt\u00a0 \u00a0<\/em><em>\u00e0\u00a0 \u00a0l<\/em><em>a\u00a0 \u00a0<\/em><em>c<\/em><em>h<\/em><em>a<\/em><em>r<\/em><em>g<\/em><em>e\u00a0 \u00a0totale\u00a0 \u00a0de\u00a0 \u00a0<\/em><em>t<\/em><em>r<\/em><em>a<\/em><em>v<\/em><em>a<\/em><em>i<\/em><em>l<\/em><em>,\u00a0\u00a0\u00a0 <\/em><em>d<\/em><em>&lsquo;<\/em><em>y\u00a0\u00a0 \u00a0<\/em><em>r<\/em><em>\u00e9<\/em><em>pon<\/em><em>d<\/em><em>r<\/em><em>e\u00a0 \u00a0<\/em><em>d<\/em><em>e\u00a0 \u00a0<\/em><em>m<\/em><em>a<\/em><em>n<\/em><em>i<\/em><em>\u00e8<\/em><em>r<\/em><em>e <\/em><em>e<\/em><em>x<\/em><em>h<\/em><em>au<\/em><em>s<\/em><em>t<\/em><em>i<\/em><em>v<\/em><em>e<\/em> <em>;<\/em><\/p>\n<p><em>Consid\u00e9rant, \u00a0quoiqu&rsquo;il en soit, \u00a0que \u00a0ce qui pr\u00e9c\u00e8de \u00a0d\u00e9montre \u00a0\u00e0 suffisance que le pr\u00e9sent dossier comporte d&rsquo;importantes lacunes,\u00a0 \u00a0voire irr\u00e9gularit\u00e9s, ne permettant pas \u00a0\u00e0 l&rsquo;autorit\u00e9 \u00a0comp\u00e9tente \u00a0sur recours \u00a0de statuer favorablement en confirmant le permis d\u00e9livr\u00e9 \u00a0en premi\u00e8re \u00a0instance \u00a0\u00bb\u00a0\u00a0<\/em><\/p>\n<p>Le point de vue de l&rsquo;autorit\u00e9 a \u00e9t\u00e9 valid\u00e9 par le conseil d&rsquo;Etat dans son arr\u00eat 247.547 du 14 mai 2020 dans les termes suivants<\/p>\n<p><em>\u00ab\u00a0En consid\u00e9rant que l&rsquo;\u00e9tude d&rsquo;incidences n&rsquo;a pas rencontr\u00e9 cet objectif, le fonctionnaire technique et l&rsquo;auteur de l&rsquo;acte attaqu\u00e9 ne commettent pas d&rsquo;erreur puisque l&rsquo;AWAC rel\u00e8ve elle-m\u00eame dans son avis que ni l&rsquo;\u00e9valuation de la situation initiale, ni l&rsquo;\u00e9valuation de la situation projet\u00e9e ne contiennent la moindre quantification des \u00e9missions de poussi\u00e8res et de particules fines, ni d&rsquo;estimation de l&rsquo;impact du projet sur le voisinage.<strong> Partant, le public n&rsquo;a pas \u00e9t\u00e9 en mesure de formuler en toute connaissance de cause des observations \u00e0 cet \u00e9gard, et notamment au \u00a0sujet \u00a0de\u00a0 l&rsquo;ad\u00e9quation \u00a0des \u00a0mesures \u00a0et \u00a0recommandations \u00a0sugg\u00e9r\u00e9es \u00a0dans \u00a0la demande, dans l&rsquo;\u00e9tude d&rsquo;incidences et dans les avis de l&rsquo;AWAC pour limiter ces nuisances.\u00a0\u00bb<\/strong><\/em><\/p>\n<p><span style=\"text-decoration: underline;\">2.4.3\/ En ce qui concerne la validation par l&rsquo;auteur de l&rsquo;\u00e9tude des incidences sur l&rsquo;environnement des \u00e9tudes tierces qu&rsquo;il int\u00e9gre dans son \u00e9valuation<\/span><\/p>\n<p><em>D<\/em><em>&lsquo;<\/em><em>u<\/em><em>n <\/em><em>p<\/em><em>o<\/em><em>i<\/em><em>n<\/em><em>t <\/em><em>d<\/em><em>e \u00a0v<\/em><em>u<\/em><em>e \u00a0l\u00e9<\/em><em>g<\/em><em>a<\/em><em>l<\/em><em>, \u00a0<\/em><em>l<\/em><em>a <\/em><em>j<\/em><em>u<\/em><em>r<\/em><em>i<\/em><em>s<\/em><em>p<\/em><em>r<\/em><em>u<\/em><em>d<\/em><em>e<\/em><em>n<\/em><em>c<\/em><em>e \u00a0<\/em><em>d<\/em><em>u \u00a0<\/em><em>C<\/em><em>o<\/em><em>ns<\/em><em>e<\/em><em>i<\/em><em>l <\/em><em>d<\/em><em>&lsquo;<\/em><em>\u00c9<\/em><em>t<\/em><em>a<\/em><em>t<\/em> <em>re<\/em><em>q<\/em><em>u<\/em><em>ie<\/em><em>rt <\/em><em>d<\/em><em>e <\/em><em>l<\/em><em>a <\/em><em>p<\/em><em>a<\/em><em>rt <\/em><em>d<\/em><em>e l&rsquo;auteur d&rsquo;E<\/em><em>I<\/em><em>E<\/em> <em>c<\/em><em>e<\/em><em>t<\/em><em>t<\/em><em>e \u00a0<\/em><em>v<\/em><em>a<\/em><em>l<\/em><em>i<\/em><em>d<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>on<\/em><em>,<\/em><em> \u00a0\u00e0 l&rsquo;\u00e9gar<\/em><em>d<\/em><em> \u00a0d<\/em><em>&lsquo;<\/em><em>a<\/em><em>i<\/em><em>ll<\/em><em>e<\/em><em>u<\/em><em>r<\/em><em>s <\/em><em>d<\/em><em>e\u00a0\u00a0 <\/em><em>t<\/em><em>o<\/em><em>u<\/em><em>t \u00a0<\/em><em>d<\/em><em>o<\/em><em>c<\/em><em>u<\/em><em>m<\/em><em>e<\/em><em>n<\/em><em>t \u00a0<\/em><em>q<\/em><em>u<\/em><em>&lsquo;<\/em><em>i<\/em><em>l \u00a0<\/em><em>i<\/em><em>n<\/em><em>t<\/em><em>\u00e8<\/em><em>g<\/em><em>r<\/em><em>e \u00a0<\/em><em>d<\/em><em>a<\/em><em>n<\/em><em>s\u00a0 \u00a0son\u00a0 \u00a0\u00e9<\/em><em>t<\/em><em>u<\/em><em>d<\/em><em>e \u00a0e<\/em><em>t \u00a0<\/em><em>v<\/em><em>e<\/em><em>n<\/em><em>a<\/em><em>n<\/em><em>t \u00a0<\/em><em>d<\/em><em>&lsquo;<\/em><em>u<\/em><em>n<\/em><em>e \u00a0<\/em><em>s<\/em><em>o<\/em><em>u<\/em><em>r<\/em><em>c<\/em><em>e e<\/em><em>x<\/em><em>t<\/em><em>\u00e9<\/em><em>r<\/em><em>i<\/em><em>e<\/em><em>u<\/em><em>r<\/em><em>e<\/em> <em>;<\/em><\/p>\n<p><em>C<\/em><em>o<\/em><em>ns<\/em><em>i<\/em><em>d<\/em><em>\u00e9<\/em><em>r<\/em><em>a<\/em><em>n<\/em><em>t <\/em><em>e<\/em><em>n <\/em><em>e<\/em><em>ff<\/em><em>e<\/em><em>t <\/em><em>qu<\/em><em>e plus<\/em><em>i<\/em><em>e<\/em><em>u<\/em><em>r<\/em><em>s <\/em><em>a<\/em><em>rr\u00eats <\/em><em>d<\/em><em>u Co<\/em><em>n<\/em><em>s<\/em><em>e<\/em><em>i<\/em><em>l <\/em><em>d<\/em><em>&lsquo;<\/em><em>\u00c9<\/em><em>t<\/em><em>a<\/em><em>t <\/em><em>(<\/em><em>n<\/em><em>\u00b0 <\/em>226. <em>7<\/em><em>9<\/em><em>8 \u00a0du\u00a0 18 mars \u00a02014<\/em><em>,\u00a0 \u00a0<\/em><em>n<\/em><em>\u00b0 233<\/em><em>.<\/em><em>63<\/em><em>9 <\/em><em>d<\/em><em>u \u00a0<\/em>26 \u00a0<em>j<\/em><em>a<\/em><em>n<\/em><em>v<\/em><em>i<\/em><em>e<\/em><em>r <\/em><em>2<\/em><em>0<\/em><em>1<\/em><em>6<\/em><em>) \u00a0<\/em><em>o<\/em><em>n<\/em><em>t\u00a0 <\/em><em>a<\/em><em>bo<\/em><em>u<\/em><em>t<\/em><em>i<\/em><em>t \u00a0<\/em><em>\u00e0 \u00a0<\/em><em>l<\/em><em>&lsquo;<\/em><em>a<\/em><em>n<\/em><em>n<\/em><em>u<\/em><em>l<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n \u00a0<\/em><em>d<\/em><em>e <\/em><em>l<\/em><em>&lsquo;<\/em><em>a<\/em><em>c<\/em><em>t<\/em><em>e <\/em><em>a<\/em><em>t<\/em><em>t<\/em><em>a<\/em><em>q<\/em><em>u<\/em><em>\u00e9 s<\/em><em>u<\/em><em>i<\/em><em>t<\/em><em>e<\/em><em> \u00a0<\/em><em>\u00e0 <\/em><em>l<\/em><em>&lsquo;<\/em><em>a<\/em><em>b<\/em><em>s<\/em><em>e<\/em><em>n<\/em><em>c<\/em><em>e \u00a0de cette \u00a0<\/em><em>v<\/em><em>a<\/em><em>l<\/em><em>i<\/em><em>d<\/em><em>a<\/em><em>t<\/em><em>i<\/em><em>o<\/em><em>n<\/em><em>;<\/em><em> \u00a0<\/em><em>q<\/em><em>u<\/em><em>e l&rsquo;<\/em><em>o<\/em><em>n<\/em> <em>p<\/em><em>e<\/em><em>u<\/em><em>t <\/em><em>y <\/em><em>li<\/em><em>r<\/em><em>e<\/em><em>:<\/em><\/p>\n<ul>\n<li>\u00ab\u00a0Afin de r\u00e9aliser l&rsquo;\u00e9tude \u00a0d&rsquo;incidences, \u00a0son \u00a0auteur \u00a0peut \u00a0utiliser \u00a0toutes \u00a0les \u00a0\u00e9tudes r\u00e9alis\u00e9es \u00a0concernant \u00a0le \u00a0site.\u00a0\u00a0 N\u00e9anmoins, \u00a0s&rsquo;il \u00a0s&rsquo;approprie \u00a0les \u00a0r\u00e9sultats \u00a0d&rsquo;une telle \u00a0\u00e9tude, \u00a0il \u00a0doit proc\u00e9der \u00e0 leur contr\u00f4le.\u00a0\u00bb \u00a0;<\/li>\n<li>\u00ab\u00a0l&rsquo;\u00e9tude \u00a0d&rsquo;incidences\u00a0\u00a0 \u00a0sur\u00a0 \u00a0l&rsquo;environnement\u00a0\u00a0 \u00a0doit\u00a0 \u00a0d\u00e9montrer\u00a0\u00a0 \u00a0que,\u00a0\u00a0\u00a0 \u00a0lorsque l&rsquo;\u00e9valuation \u00a0d&rsquo;un \u00a0des \u00a0crit\u00e8res \u00a0techniques \u00a0a\u00a0\u00a0 \u00e9t\u00e9 \u00a0d\u00e9l\u00e9gu\u00e9e \u00a0\u00e0 \u00a0un \u00a0autre \u00a0bureau technique, \u00a0l&rsquo;auteur \u00a0de\u00a0 l&rsquo;\u00e9tude \u00a0d&rsquo;incidences \u00a0a \u00a0bien \u00a0lui-m\u00eame \u00a0r\u00e9alis\u00e9 un contr\u00f4le des r\u00e9sultats, &#8230; \u00a0\u00bb \u00a0;<\/li>\n<li>\u00ab\u00a0l&rsquo;effectivit\u00e9 \u00a0du\u00a0 \u00a0contr\u00f4le\u00a0 \u00a0op\u00e9r\u00e9 \u00a0par \u00a0l&rsquo;auteur\u00a0 \u00a0de\u00a0 \u00a0l&rsquo;\u00e9tude\u00a0 \u00a0d&rsquo;incidences\u00a0 \u00a0sur \u00a0les informations \u00a0lui \u00a0\u00e9tant\u00a0 transmises \u00a0par \u00a0des \u00a0bureaux \u00a0d&rsquo;expertise \u00a0tiers \u00a0est \u00a0un \u00e9l\u00e9ment d\u00e9terminant \u00a0de\u00a0 la \u00a0l\u00e9galit\u00e9 \u00a0de\u00a0 l&rsquo;\u00e9tude \u00a0d&rsquo;incidences \u00a0sur l&rsquo;environnement et \u00a0du\u00a0 permis \u00a0finalement d\u00e9livr\u00e9\u00a0\u00bb ;<\/li>\n<li>\u00ab\u00a0&#8230;il y \u00a0a \u00a0lieu \u00a0de \u00a0rappeler que \u00a0l&rsquo;article \u00a0R.59, \u00a0\u00a7 \u00a01er, \u00a03\u00b0, du \u00a0Livre Ier \u00a0du \u00a0Code \u00a0de l&rsquo;environnement impose \u00a0au demandeur d&rsquo;agr\u00e9ment comme \u00a0auteur d&rsquo;\u00e9tudes d&rsquo;incidences\u00a0\u00a0 d&rsquo;avoir \u00a0les\u00a0\u00a0 comp\u00e9tences\u00a0 \u00a0n\u00e9cessaires\u00a0 \u00a0pour \u00a0\u00ab\u00a0exploiter \u00a0tous \u00a0les r\u00e9sultats y compris ceux \u00a0de la\u00a0 sous-traitance\u00a0\u00bb \u00a0;\u00a0 \u00a0qu&rsquo;il en r\u00e9sulte que \u00a0l&rsquo;auteur de l&rsquo;\u00e9tude \u00a0d&rsquo;incidences \u00a0doit \u00eatre \u00a0en \u00a0mesure \u00a0de \u00a0contr\u00f4ler\u00a0 ces \u00a0r\u00e9sultats \u00a0et \u00a0que \u00a0la r\u00e9alit\u00e9 \u00a0de ce contr\u00f4le \u00a0doit ressortir de l&rsquo;\u00e9tude \u00a0d&rsquo;incidences \u00a0elle-m\u00eame \u00bb;<\/li>\n<\/ul>\n<p>Au niveau des modalit\u00e9s pratiques, le conseil d&rsquo;Etat enseigne:<\/p>\n<ul>\n<li>La r\u00e9alit\u00e9 de ce contr\u00f4le se manifeste par exemple par un document \u00e9labor\u00e9 par l&rsquo;auteur de l&rsquo;\u00e9tude d&rsquo;incidences et intitul\u00e9 \u00ab\u00a0Validation du calcul de productible d&rsquo;un projet \u00e9olien avec bridage acoustique\u00a0\u00bb, dont la lecture par le conseil d&rsquo;\u00e9tant permet de s&rsquo;assurer que le contr\u00f4le par l&rsquo;auteur de l&rsquo;\u00e9tude d&rsquo;incidences n&rsquo;a pas \u00e9t\u00e9 de pure forme (CE, 11 avril 2016, Jooris et crts, n\u00b0234.327, p. 10)<\/li>\n<li>L&rsquo;unique affirmation selon laquelle \u00ab\u00a0Le travail par le bureau d&rsquo;\u00e9tude Gestamp Eolica a \u00e9t\u00e9 contr\u00f4le par l&rsquo;auteur de l&rsquo;\u00e9tude d&rsquo;incidences ne suffit pas\u00a0\u00bb (CE, 26 octobre 2015, Commune de Braives, n\u00b0232.690, p. 14)<\/li>\n<li>L&rsquo;\u00e9tude sp\u00e9cialis\u00e9e doit \u00eatre jointe \u00e0 l&rsquo;\u00e9tude d&rsquo;incidences et un contr\u00f4le doit \u00eatre exerc\u00e9 par l&rsquo;auteur de l&rsquo;\u00e9tude d&rsquo;incidence (CE, 8 f\u00e9vrier 2019, Commune de Tinlot, n\u00b0237.313, p. 9)<\/li>\n<\/ul>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2\/ En ce qui concerne l&rsquo;\u00e9valuation des incidences du projet sur l\u2019environnement 2.1\/ Introduction \u00e0 la mati\u00e8re 2.1.1\/ Base l\u00e9gale On rappellera que le si\u00e8ge de la mati\u00e8re est situ\u00e9 aux articles D.62 et svts du livre 1er du code de l\u2019environnement, qui indiquent: D.62.\u00a0[\u00a7 1er. Toute demande de permis comporte soit une notice d\u2019\u00e9valuation &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/analyse-juridique-dune-carriere\/elements-danalyse-dun-permis-carrier\/analyse-des-incidences-sur-lenvironnement-dun-permis-carrier\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Analyse des incidences sur l&rsquo;environnement d&rsquo;un permis carrier&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2239,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/pages\/4843"}],"collection":[{"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/comments?post=4843"}],"version-history":[{"count":13,"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/pages\/4843\/revisions"}],"predecessor-version":[{"id":5153,"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/pages\/4843\/revisions\/5153"}],"up":[{"embeddable":true,"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/pages\/2239"}],"wp:attachment":[{"href":"https:\/\/xn--riveraindecarrire-6sb.be\/index.php\/wp-json\/wp\/v2\/media?parent=4843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}